{"id":380,"date":"2019-01-29T12:22:01","date_gmt":"2019-01-29T11:22:01","guid":{"rendered":"http:\/\/netphiltech.org\/wordpress\/?post_type=tribe_events&#038;p=380"},"modified":"2019-01-29T12:29:06","modified_gmt":"2019-01-29T11:29:06","slug":"physiopsychologische-aspekte-in-nietzsches-erkenntniskritik","status":"publish","type":"tribe_events","link":"https:\/\/netphiltech.org\/wordpress\/event\/physiopsychologische-aspekte-in-nietzsches-erkenntniskritik\/","title":{"rendered":"Physiopsychologische Aspekte in Nietzsches Erkenntniskritik"},"content":{"rendered":"<p>Seit seinem ersten Buch ist eine physiopsychologische Sicht in der Philosophie Nietzsches anwesend. Sie zeigt sich haupts\u00e4chlich in seiner Kritik der metaphysichen Philosophie und der Wissenschaft. Trotzdem bringt sie nicht nur destruktive Aspekte mit sich, sondern erweist sich als sehr hilfreich, um die Wissensperpektive Nietzsches zu verstehen. Der Vortrag zielt darauf, diese Aspekte in ihrer Komplexit\u00e4t in Nietzsches Denken zu betrachten.<\/p>\n<p>Ort: Der Ort der Veranstaltung wird nach der Anmeldung bekannt gegeben.<br \/>\nKosten: Die Teilnahme ist kostenfrei.<br \/>\nAnmeldung: Anmeldungen bitte bis sp\u00e4testens 08.02.2019 per E-Mail an<br \/>\nevents [at] netphiltech.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit seinem ersten Buch ist eine physiopsychologische Sicht in der Philosophie Nietzsches anwesend. Sie zeigt sich haupts\u00e4chlich in seiner Kritik der metaphysichen Philosophie und der Wissenschaft. Trotzdem bringt sie nicht &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/netphiltech.org\/wordpress\/event\/physiopsychologische-aspekte-in-nietzsches-erkenntniskritik\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201ePhysiopsychologische Aspekte in Nietzsches Erkenntniskritik\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":""},"tags":[44,40,41,42,43],"tribe_events_cat":[],"_links":{"self":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tribe_events\/380"}],"collection":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tribe_events\/380\/revisions"}],"predecessor-version":[{"id":383,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tribe_events\/380\/revisions\/383"}],"wp:attachment":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/media?parent=380"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tags?post=380"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tribe_events_cat?post=380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}