{"id":568,"date":"2020-10-05T19:04:00","date_gmt":"2020-10-05T17:04:00","guid":{"rendered":"http:\/\/netphiltech.org\/wordpress\/?p=568"},"modified":"2022-01-20T19:24:45","modified_gmt":"2022-01-20T18:24:45","slug":"philosophisches-fruehstueck-chinesisches-matineezimmer","status":"publish","type":"post","link":"https:\/\/netphiltech.org\/wordpress\/2020\/10\/05\/philosophisches-fruehstueck-chinesisches-matineezimmer\/","title":{"rendered":"Philosophisches Fr\u00fchst\u00fcck &#8211; Chinesisches Matineezimmer"},"content":{"rendered":"\n<p>Im September 2020 waren wir zu Gast bei den <a href=\"https:\/\/datenspuren.de\/2020\/\">Datenspuren<\/a> vom <a href=\"https:\/\/c3d2.de\/\">C3D2<\/a> in Dresden. Zum Hacker-Sonntagvormittag wurde traditionsgem\u00e4\u00df ein wenig philosophische Unterhaltung und Erbauung angeboten. Nach dem Vorbild des <a href=\"https:\/\/de.wikipedia.org\/wiki\/Chinesisches_Zimmer\">Chinesischen Zimmers<\/a> haben wir dabei einen invertierten <a href=\"https:\/\/de.wikipedia.org\/wiki\/Turing-Test\">Turing-Test<\/a> durchlebt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Unter dem Thema &#8222;Mehr Utopie wagen&#8220; haben wir uns bei den Datenspuren 2020 einem klassischen Gedankenexperiment gewidmet: dem Chinesischen Zimmer von John Searle. Doch was, wenn es sich nicht um die chinesische Sprache, sondern um Philosophie handelte? Was, wenn es nicht um die Frage der Intelligenz in Maschinen, sondern um die Intelligenz in der Fachliteratur ginge?<\/p>\n\n\n\n<p>Um das Gedankenexperiment einmal wahr werden zu lassen, waren wir zu viert, mit gro\u00dfen Stapeln an Enzyklop\u00e4dien, W\u00f6rterb\u00fcchern, Fachliteratur und digitalen Hilfsmitteln in unserer Gesch\u00e4ftsstelle im Zentralwerk in Dresden. \u00dcber den Stream und den Chat konnten die Besucher mehr oder weniger philosophische Fragen stellen und mehr oder weniger philosophische Antworten erhalten &#8211; was Literatur, Hilfsmittel und k\u00fcnstlerische Freiheit eben im eiligen Gebrauch hergeben. Ob und wie viele &#8222;k\u00fcnstliche Intelligenzen&#8220; an dem Beitrag beteiligt waren, bleibt ungewiss. Mehr im Video:<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/media.ccc.de\/v\/ds20-11312-philosophisches_fruhstuck\/oembed\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe>\n\n\n\n<p>Wir danken herzlich f\u00fcr die sch\u00f6ne Veranstaltung und die M\u00f6glichkeit zur Mitwirkung!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im September 2020 waren wir zu Gast bei den Datenspuren vom C3D2 in Dresden. Zum Hacker-Sonntagvormittag wurde traditionsgem\u00e4\u00df ein wenig philosophische Unterhaltung und Erbauung angeboten. Nach dem Vorbild des Chinesischen Zimmers haben wir einen invertierten Turing-Test angeboten.<\/p>\n","protected":false},"author":1,"featured_media":564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[68,12,23,70,69],"_links":{"self":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/568"}],"collection":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/comments?post=568"}],"version-history":[{"count":8,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/568\/revisions"}],"predecessor-version":[{"id":578,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/568\/revisions\/578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/media\/564"}],"wp:attachment":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/media?parent=568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/categories?post=568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tags?post=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}