{"id":464,"date":"2019-06-22T12:59:50","date_gmt":"2019-06-22T10:59:50","guid":{"rendered":"http:\/\/netphiltech.org\/wordpress\/?p=464"},"modified":"2019-08-22T11:26:39","modified_gmt":"2019-08-22T09:26:39","slug":"vortragsankuendigung-bernhard-irrgang-die-mensch-maschinen-interaktion-hci-epistemologische-und-ethische-probleme","status":"publish","type":"post","link":"https:\/\/netphiltech.org\/wordpress\/2019\/06\/22\/vortragsankuendigung-bernhard-irrgang-die-mensch-maschinen-interaktion-hci-epistemologische-und-ethische-probleme\/","title":{"rendered":"Die Mensch-Maschinen-Interaktion (HCI): epistemologische und ethische Probleme"},"content":{"rendered":"\n<p><br> <br> Am Montag, den 24. Juni 2019, wird Bernhard Irrgang von 16:40 bis 18:10 Uhr im Rahmen des Graduiertenkollegs \u201cF\u00f6rderliche Gestaltung cyber-physischer Produktionssysteme\u201d \u00fcber epistemologische und ethische Probleme in der Mensch-Maschinen-Interaktion sprechen. Der Vortrag findet im Raum 201 des H\u00f6rsaalzentrums der TU Dresden statt.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Die HCI ist eines der wichtigsten Projekte in der Transformation der industriellen Moderne in eine Hypermoderne Technologie-Zivilisation mit entsprechenden technologischen, gesellschaftlichen (\u00f6konomischen und politischen) und kulturellen Transformationen. Einige der philosophisch relevanten Rahmenbedingungen sollen vorgestellt werden vor dem Hintergrund der Unterscheidung von technischer Konstruktion (technologischem Design) und Nutzungsformen von k\u00fcnstlicher Intelligenz. Hierbei spielt das Problem der Anthropomorphisierung eine zentrale methodische Rolle.<br>In einem zweiten Schritt wird KI in die Geschichte der europ\u00e4ischen Rationalit\u00e4t zwischen mathematisch orientierter reiner Vernunft (Hobbes, Descartes, Kant) und dem klassischen Leib-Seele-Problem (heute Brain-Mind-Problem oder in eine evolution\u00e4re Anthropologie des leiblich eingebetteten personal Mentalen; Leibniz, Merlau-Ponty, Plessner) eingeordnet. Dabei spielen die in der Metamathematik erarbeiteten Grenzen der Berechenbarkeit als Voraussetzung der Computer-Epistemologie der von Neumann-Architektur eine zentrale Rolle. Auf dieser Basis kann eine philosophisch-methodologisch abgesicherte Er\u00f6rterung der HCI-Problematik erfolgen.<br>Die Konvergenz im Umgang mit KI (HCI), Nanotechnologien und transformativer Biotechnologie wird einen umfangreichen Technologiewandel erzeugen (basierend auf der Technologieentwicklung, welche von Bernhard Irrgang in seinem Buch \u201eVon der technischen Konstruktion zum technologischen Design\u201c (2010) technikwissenschaftlich und philosophisch beschrieben wurde). Sie wird von umfangreichen Wertewandelprozessen begleitet sein, die in den letzten 40 Jahren in allen Bereichen von Wissenschaft und Technologie zumindest angefangen haben. Die ethischen Prinzipien, formuliert \u00fcberwiegend im Paradigma des europ\u00e4ischen Rationalismus, kommen dabei wie das Rationalit\u00e4tskonzept der (industriellen) Moderne an ihre Grenzen. Offenbar wurde dies zum Beispiel in der Diskussion um KI und HCI in der zweiten H\u00e4lfte der achtziger Jahre durch die Gebr\u00fcder Dreyfus und Weizenbaum. Diese entwickelten eine Konzeption der ethischen Expertise und des Expertentums im Umgang mit KI-Technologie, denen auf ethischer Ebene zum Beispiel Irrgangs Konzeption einer Hermeneutischen Ethik korrespondiert. Diese kann zwar durch KI-Modellierung in wesentlichen Bereichen unterst\u00fctzt und pr\u00e4zisiert, aber nicht ersetzt werden. Routinisiertes Alltagsverhalten l\u00e4sst sich also auch von Expertensystemen durchf\u00fchren, ethisch problematische Situationen sollten allerdings weiterhin von menschlichen Experten bewertet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Montag, den 24. Juni 2019, wird Bernhard Irrgang von 16:40 bis 18:10 Uhr im Rahmen des Graduiertenkollegs \u201cF\u00f6rderliche Gestaltung cyber-physischer Produktionssysteme\u201d \u00fcber epistemologische und ethische Probleme in der Mensch-Maschinen-Interaktion &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/netphiltech.org\/wordpress\/2019\/06\/22\/vortragsankuendigung-bernhard-irrgang-die-mensch-maschinen-interaktion-hci-epistemologische-und-ethische-probleme\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDie Mensch-Maschinen-Interaktion (HCI): epistemologische und ethische Probleme\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[57,58,49,20],"_links":{"self":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/464"}],"collection":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":5,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/464\/revisions"}],"predecessor-version":[{"id":474,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/posts\/464\/revisions\/474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/media\/299"}],"wp:attachment":[{"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/media?parent=464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/categories?post=464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/netphiltech.org\/wordpress\/wp-json\/wp\/v2\/tags?post=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}